{"id":2393,"date":"2024-06-09T05:31:30","date_gmt":"2024-06-09T05:31:30","guid":{"rendered":"https:\/\/nylon-granules.com\/?p=2393"},"modified":"2024-06-09T05:55:00","modified_gmt":"2024-06-09T05:55:00","slug":"water-absorption-reduction-of-modified-pa6","status":"publish","type":"post","link":"https:\/\/nylon-granules.com\/de\/water-absorption-reduction-of-modified-pa6\/","title":{"rendered":"Grundlagen der Verringerung der Wasserabsorption von modifiziertem PA6"},"content":{"rendered":"<div class=\"row\"  id=\"row-2023246567\">\n\n\t<div id=\"col-98246278\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalts\u00fcbersicht<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Inhaltsverzeichnis umschalten\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Umschalten auf<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nylon-granules.com\/de\/water-absorption-reduction-of-modified-pa6\/#Introduction_of_PA6\" >Einf\u00fchrung von PA6<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nylon-granules.com\/de\/water-absorption-reduction-of-modified-pa6\/#Methods_to_Reduce_Water_Absorption_in_PA6\" >Methoden zur Verringerung der Wasseraufnahme in PA6<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nylon-granules.com\/de\/water-absorption-reduction-of-modified-pa6\/#Understanding_the_Core_Principles\" >Verstehen der Grundprinzipien<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nylon-granules.com\/de\/water-absorption-reduction-of-modified-pa6\/#Conclusion\" >Schlussfolgerung<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Introduction_of_PA6\"><\/span><strong>Einf\u00fchrung von PA6<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>PA6, oder Nylon 6, ist ein weit verbreiteter technischer Kunststoff, der f\u00fcr seine Festigkeit, Haltbarkeit und Vielseitigkeit bekannt ist. Seine Anf\u00e4lligkeit f\u00fcr Wasseraufnahme kann jedoch bei Anwendungen, bei denen Dimensionsstabilit\u00e4t und Leistung in feuchten Umgebungen entscheidend sind, zu Problemen f\u00fchren. Zur L\u00f6sung dieses Problems wurden Verfahren zur Modifizierung von PA6 entwickelt, die die Wasseraufnahme wirksam verringern und die Gesamtleistung des Materials verbessern.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1532529478\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_26841991\">\n\t\t<a class=\"\" href=\"https:\/\/nylon-granules.com\/de\/products\/nylon-6\/\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/06\/PA6-1-768x1024.webp\" class=\"attachment-medium_large size-medium_large\" alt=\"PA6\" srcset=\"https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/06\/PA6-1-768x1024.webp 768w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/06\/PA6-1-225x300.webp 225w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/06\/PA6-1-9x12.webp 9w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/06\/PA6-1-600x800.webp 600w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/06\/PA6-1.webp 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_26841991 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"Methods_to_Reduce_Water_Absorption_in_PA6\"><\/span><strong>Methoden zur Verringerung der Wasseraufnahme in PA6<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Um die Wasseraufnahme von PA6 zu verringern, werden in der Regel drei Ans\u00e4tze verfolgt:<\/p>\n<ol>\n<li><strong>Co-Modifikationsmittel:<\/strong>Die Zugabe von Co-Modifizierungsmitteln, wie lldp, PP oder Maleins\u00e4ureanhydrid-Polymerisation, ver\u00e4ndert die chemische Struktur von PA6 und verringert die Anzahl der polaren Gruppen, die Wassermolek\u00fcle anziehen.<\/li>\n<li><strong>Organische F\u00fcllstoffe:<\/strong>Die Einbindung organischer F\u00fcllstoffe wie Kalziumkarbonat oder leichtes Kalziumkarbonat in die PA6-Matrix schr\u00e4nkt die Bewegung von Wassermolek\u00fclen physikalisch ein und behindert deren Diffusion in das Material.<\/li>\n<li><strong>Oberfl\u00e4chenbehandlung und -ver\u00e4nderung:<\/strong>Die Modifizierung der Oberfl\u00e4che von PA6, entweder durch chemische oder physikalische Behandlungen, schafft eine Barriere, die das Eindringen von Wasser verhindert und die Wasseraufnahme insgesamt reduziert.<\/li>\n<\/ol>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Understanding_the_Core_Principles\"><\/span><strong>Verstehen der Grundprinzipien<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Wirksamkeit der <a href=\"https:\/\/nylon-granules.com\/de\/products\/nylon-6\/pa6-glass-fiber\/\">PA6-\u00c4nderung<\/a> zur Verringerung der Wasseraufnahme beruht auf drei Grundprinzipien:<\/p>\n<ul>\n<li><strong>Polarit\u00e4t abschirmende Wirkung:<\/strong>Durch die Einf\u00fchrung unpolarer oder weniger polarer Gruppen in die PA6-Struktur wird die Anziehungskraft zwischen PA6 und Wassermolek\u00fclen durch den Abschirmungseffekt verringert und die Wasseraufnahme minimiert.<\/li>\n<li><strong>Kristallisation Abschirmende Wirkung:<\/strong>Die Erh\u00f6hung der Kristallinit\u00e4t von PA6 durch Modifizierungsverfahren verringert die amorphen Bereiche, in denen sich Wassermolek\u00fcle ansammeln k\u00f6nnen, was zu einer geringeren Wasseraufnahme f\u00fchrt.<\/li>\n<li><strong>Strukturelle abschirmende Wirkung:<\/strong>Durch die Zugabe von F\u00fcllstoffen oder Oberfl\u00e4chenmodifikatoren wird eine physikalische Barriere geschaffen, die den direkten Kontakt zwischen PA6 und Wasser verhindert und die Wasseraufnahme weiter reduziert.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span><strong>Schlussfolgerung<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Modifizierung von PA6 bietet einen vielseitigen Ansatz zur Verbesserung seiner Wasserbest\u00e4ndigkeit und zur Erweiterung seines Anwendungsbereichs. Wenn wir die zugrunde liegenden Prinzipien dieser Modifizierungsverfahren verstehen, k\u00f6nnen wir PA6 effektiv auf spezifische Anwendungen zuschneiden, die au\u00dfergew\u00f6hnliche Leistungen in feuchten Umgebungen erfordern.<\/p>","protected":false},"excerpt":{"rendered":"<p>Methoden zur Verringerung der Wasseraufnahme in PA6 Drei Hauptans\u00e4tze werden \u00fcblicherweise angewandt, um die Wasseraufnahme in PA6 zu verringern: Co-Modifizierungsmittel: Durch die Zugabe von Co-Modifizierungsmitteln, wie lldp, PP oder Maleins\u00e4ureanhydridpolymerisation, wird die chemische Struktur von PA6 ver\u00e4ndert und die Anzahl der polaren Gruppen, die Wassermolek\u00fcle anziehen, verringert. Organische F\u00fcllstoffe: Die Zugabe von organischen F\u00fcllstoffen, wie Kalziumkarbonat [...]","protected":false},"author":1,"featured_media":2396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-2393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nylon"],"_links":{"self":[{"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/posts\/2393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/comments?post=2393"}],"version-history":[{"count":4,"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/posts\/2393\/revisions"}],"predecessor-version":[{"id":2399,"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/posts\/2393\/revisions\/2399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/media\/2396"}],"wp:attachment":[{"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/media?parent=2393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/categories?post=2393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nylon-granules.com\/de\/wp-json\/wp\/v2\/tags?post=2393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}