{"id":2865,"date":"2024-07-13T01:54:59","date_gmt":"2024-07-13T01:54:59","guid":{"rendered":"https:\/\/nylon-granules.com\/?p=2865"},"modified":"2024-07-13T02:24:31","modified_gmt":"2024-07-13T02:24:31","slug":"nylon-12-cf-performance-for-various-application","status":"publish","type":"post","link":"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/","title":{"rendered":"Nylon 12 CF haute performance pour diverses applications"},"content":{"rendered":"<div class=\"row\"  id=\"row-1318353895\">\n\n\t<div id=\"col-1348109154\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table des mati\u00e8res\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Introduction_of_Nylon_12_CF\" >Introduction du Nylon 12 CF<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Exceptional_Mechanical_Properties_of_Nylon_12_CF\" >Propri\u00e9t\u00e9s m\u00e9caniques exceptionnelles du Nylon 12 CF<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Superior_Chemical_Resistance_of_Nylon_12_CF\" >R\u00e9sistance chimique sup\u00e9rieure du nylon 12 CF<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Outstanding_Thermal_Properties_of_Nylon_12_CF\" >Propri\u00e9t\u00e9s thermiques exceptionnelles du nylon 12 CF<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Excellent_Processability_of_Nylon_12_CF\" >Excellente aptitude au traitement du Nylon 12 CF<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Applications_in_the_Automotive_Industry\" >Applications dans l'industrie automobile<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Applications_in_the_Aerospace_Industry\" >Applications dans l'industrie a\u00e9rospatiale<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Applications_in_the_Medical_Industry\" >Applications dans l'industrie m\u00e9dicale<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Applications_in_the_Electrical_Industry\" >Applications dans l'industrie \u00e9lectrique<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Conclusion_of_Nylon_12_CF\" >Conclusion du Nylon 12 CF<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/nylon-granules.com\/fr\/nylon-12-cf-performance-for-various-application\/#Summary_FAQ_on_Nylon_12_CF\" >FAQ r\u00e9capitulative sur le Nylon 12 CF<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Introduction_of_Nylon_12_CF\"><\/span><strong><b>Introduction du Nylon 12 CF<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le Nylon 12 CF, un polym\u00e8re de haute performance, a fait l'objet d'une attention particuli\u00e8re ces derni\u00e8res ann\u00e9es en raison de ses propri\u00e9t\u00e9s exceptionnelles qui en font un choix id\u00e9al pour diverses applications. Ce polym\u00e8re, \u00e9galement connu sous le nom de <a href=\"https:\/\/nylon-granules.com\/fr\/products\/nylon-12\/\">nylon 12<\/a> renforc\u00e9 de fibres de carbone, est un mat\u00e9riau composite qui combine la r\u00e9sistance et la rigidit\u00e9 des fibres de carbone avec les propri\u00e9t\u00e9s chimiques et m\u00e9caniques du nylon 12.\u00a0<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1956682819\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_520599384\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1440\" src=\"https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-12-CF.jpeg\" class=\"attachment-original size-original\" alt=\"Nylon 12 CF\" srcset=\"https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-12-CF.jpeg 1080w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-12-CF-225x300.jpeg 225w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-12-CF-768x1024.jpeg 768w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-12-CF-9x12.jpeg 9w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_520599384 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<h2><span class=\"ez-toc-section\" id=\"Exceptional_Mechanical_Properties_of_Nylon_12_CF\"><\/span><strong><b>Propri\u00e9t\u00e9s m\u00e9caniques exceptionnelles du Nylon 12 CF<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il offre des propri\u00e9t\u00e9s m\u00e9caniques exceptionnelles qui en font un choix privil\u00e9gi\u00e9 pour les applications de haute performance. Le renforcement en fibres de carbone conf\u00e8re au mat\u00e9riau une rigidit\u00e9 et une r\u00e9sistance \u00e9lev\u00e9es, ce qui permet de l'utiliser dans des applications structurelles o\u00f9 la r\u00e9duction du poids est essentielle. En outre, le Nylon 12 CF pr\u00e9sente une excellente r\u00e9sistance \u00e0 la fatigue, ce qui le rend id\u00e9al pour les applications o\u00f9 l'on s'attend \u00e0 des charges cycliques.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Superior_Chemical_Resistance_of_Nylon_12_CF\"><\/span><strong><b>R\u00e9sistance chimique sup\u00e9rieure <\/b><\/strong><strong><b>Nylon 12 CF<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le Nylon 12 CF pr\u00e9sente une excellente r\u00e9sistance chimique, ce qui permet de l'utiliser dans des environnements difficiles. Ce polym\u00e8re r\u00e9siste \u00e0 une large gamme de produits chimiques, y compris les acides, les bases et les solvants, ce qui le rend id\u00e9al pour une utilisation dans l'industrie du traitement chimique. En outre, il poss\u00e8de d'excellentes propri\u00e9t\u00e9s d'isolation \u00e9lectrique, ce qui permet de l'utiliser dans des applications \u00e9lectriques o\u00f9 l'isolation est essentielle.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Outstanding_Thermal_Properties_of_Nylon_12_CF\"><\/span><strong><b>Propri\u00e9t\u00e9s thermiques exceptionnelles des <\/b><\/strong><strong><b>Nylon 12 CF<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le Nylon 12-CF poss\u00e8de d'excellentes propri\u00e9t\u00e9s thermiques, ce qui permet de l'utiliser dans des applications \u00e0 haute temp\u00e9rature. Le polym\u00e8re a une temp\u00e9rature de transition vitreuse \u00e9lev\u00e9e (Tg) d'environ 150\u00b0C, ce qui permet de l'utiliser dans des applications o\u00f9 l'on s'attend \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es. En outre, il pr\u00e9sente une excellente r\u00e9sistance au fluage, ce qui permet de l'utiliser dans des applications o\u00f9 l'on s'attend \u00e0 une exposition \u00e0 long terme \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Excellent_Processability_of_Nylon_12_CF\"><\/span><strong><b>Excellente aptitude \u00e0 la transformation des <\/b><\/strong><strong><b>Nylon 12 CF<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le Nylon 12-CF pr\u00e9sente une excellente aptitude \u00e0 la transformation, ce qui permet de l'utiliser dans divers proc\u00e9d\u00e9s de fabrication. Ce polym\u00e8re peut \u00eatre facilement transform\u00e9 \u00e0 l'aide de diverses techniques de fabrication, notamment le moulage par injection, le moulage par compression et l'extrusion. En outre, il poss\u00e8de d'excellentes propri\u00e9t\u00e9s d'\u00e9coulement, ce qui permet de l'utiliser dans des applications \u00e0 parois minces o\u00f9 l'\u00e9coulement est essentiel.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Applications_in_the_Automotive_Industry\"><\/span><strong><b>Applications dans l'industrie automobile<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les applications potentielles du Nylon 12-CF sont vastes et vari\u00e9es et couvrent plusieurs secteurs. Dans l'industrie automobile, le Nylon 12-CF est utilis\u00e9 dans diverses applications structurelles, notamment les composants du moteur, les panneaux de carrosserie et les composants du ch\u00e2ssis. La rigidit\u00e9 et la r\u00e9sistance \u00e9lev\u00e9es du mat\u00e9riau, associ\u00e9es \u00e0 son excellente r\u00e9sistance chimique, en font un choix id\u00e9al pour ces applications.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Applications_in_the_Aerospace_Industry\"><\/span><strong><b>Applications dans l'industrie a\u00e9rospatiale<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Dans l'industrie a\u00e9rospatiale, le Nylon 12-CF est utilis\u00e9 dans diverses applications structurelles, notamment dans les composants d'avions, tels que les longerons d'ailes, les composants de trains d'atterrissage et les composants de moteurs. La rigidit\u00e9 et la solidit\u00e9 \u00e9lev\u00e9es du mat\u00e9riau, associ\u00e9es \u00e0 son excellente r\u00e9sistance \u00e0 la fatigue, en font un choix id\u00e9al pour ces applications.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Applications_in_the_Medical_Industry\"><\/span><strong><b>Applications dans l'industrie m\u00e9dicale<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Dans l'industrie m\u00e9dicale, le Nylon 12-CF est utilis\u00e9 dans divers dispositifs m\u00e9dicaux, tels que les implants, les cath\u00e9ters et les instruments chirurgicaux. L'excellente biocompatibilit\u00e9 du mat\u00e9riau, combin\u00e9e \u00e0 son excellente r\u00e9sistance chimique, en fait un choix id\u00e9al pour ces applications.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Applications_in_the_Electrical_Industry\"><\/span><strong><b>Applications dans l'industrie \u00e9lectrique<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Dans l'industrie \u00e9lectrique, le Nylon 12-CF est utilis\u00e9 dans diverses applications \u00e9lectriques, telles que l'isolation \u00e9lectrique, les connecteurs et les disjoncteurs. Les excellentes propri\u00e9t\u00e9s d'isolation \u00e9lectrique du mat\u00e9riau, combin\u00e9es \u00e0 son excellente r\u00e9sistance chimique, en font un choix id\u00e9al pour ces applications.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion_of_Nylon_12_CF\"><\/span><strong><b>Conclusion <\/b><\/strong><strong><b>Nylon 12 CF<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En conclusion, le Nylon 12 CF est un polym\u00e8re de haute performance qui offre des propri\u00e9t\u00e9s exceptionnelles pour diverses applications. Ses propri\u00e9t\u00e9s m\u00e9caniques, chimiques, thermiques et de mise en \u0153uvre exceptionnelles en font un choix id\u00e9al pour diverses industries, notamment l'automobile, l'a\u00e9rospatiale, la m\u00e9decine et l'\u00e9lectricit\u00e9. Alors que la demande de mat\u00e9riaux haute performance continue de cro\u00eetre, le Nylon 12-CF est appel\u00e9 \u00e0 jouer un r\u00f4le important dans diverses applications, en stimulant l'innovation et la croissance dans diverses industries.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Summary_FAQ_on_Nylon_12_CF\"><\/span><strong><b>FAQ r\u00e9capitulative sur le Nylon 12 CF<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h4><strong><b>1. Qu'est-ce que le Nylon 12 CF ?<\/b><\/strong><\/h4>\n<p>Le nylon 12-CF, \u00e9galement connu sous le nom de nylon 12 renforc\u00e9 de fibres de carbone, est un composite polym\u00e8re de haute performance qui combine la r\u00e9sistance et la rigidit\u00e9 des fibres de carbone avec les propri\u00e9t\u00e9s chimiques et m\u00e9caniques du nylon 12 renforc\u00e9 de fibres de carbone. <a href=\"https:\/\/nylon-granules.com\/fr\/products\/nylon-12\/pa12-resin\/\">nylon 12<\/a>.<\/p>\n<p>\u00a0<\/p>\n<h4><strong><b>2. Quelles sont les principales propri\u00e9t\u00e9s m\u00e9caniques du Nylon 12 CF ?<\/b><\/strong><\/h4>\n<p>Le Nylon 12-CF offre une rigidit\u00e9 et une r\u00e9sistance \u00e9lev\u00e9es gr\u00e2ce \u00e0 son renforcement en fibres de carbone. Il pr\u00e9sente \u00e9galement une excellente r\u00e9sistance \u00e0 la fatigue, ce qui le rend adapt\u00e9 aux applications structurelles pour lesquelles la r\u00e9duction du poids et la charge cyclique sont essentielles.<\/p>\n<p>\u00a0<\/p>\n<h4><strong><b>3. Quelles sont les performances du Nylon 12 CF dans les environnements chimiques difficiles ?<\/b><\/strong><\/h4>\n<p>Le Nylon 12-CF pr\u00e9sente une excellente r\u00e9sistance chimique, ce qui permet de l'utiliser dans des environnements expos\u00e9s aux acides, aux bases et aux solvants. Cette propri\u00e9t\u00e9 le rend id\u00e9al pour les applications dans l'industrie chimique.<\/p>\n<p>\u00a0<\/p>\n<h4><strong><b>4. Quelles sont les propri\u00e9t\u00e9s thermiques du Nylon 12 CF ?<\/b><\/strong><\/h4>\n<p>Le Nylon 12-CF a une temp\u00e9rature de transition vitreuse (Tg) \u00e9lev\u00e9e d'environ 150\u00b0C, ce qui le rend adapt\u00e9 aux applications \u00e0 haute temp\u00e9rature. Il pr\u00e9sente \u00e9galement une excellente r\u00e9sistance au fluage, ce qui est important pour les applications n\u00e9cessitant une exposition \u00e0 long terme \u00e0 des temp\u00e9ratures \u00e9lev\u00e9es.<\/p>\n<p>\u00a0<\/p>\n<h4><strong><b>5. Le Nylon 12 CF est-il facile \u00e0 mettre en \u0153uvre dans la fabrication ?<\/b><\/strong><\/h4>\n<p>Oui, le Nylon 12-CF pr\u00e9sente une excellente aptitude \u00e0 la transformation et peut \u00eatre facilement trait\u00e9 \u00e0 l'aide de diverses techniques de fabrication, notamment le moulage par injection, le moulage par compression et l'extrusion. Il poss\u00e8de \u00e9galement de bonnes propri\u00e9t\u00e9s d'\u00e9coulement, ce qui le rend adapt\u00e9 aux applications \u00e0 parois minces.<\/p>\n<p>\u00a0<\/p>\n<h4><strong><b>6. Quelles sont les applications du Nylon 12 CF dans l'industrie automobile ?<\/b><\/strong><\/h4>\n<p>Dans l'industrie automobile, le Nylon 12-CF est utilis\u00e9 pour les composants du moteur, les panneaux de carrosserie et les composants du ch\u00e2ssis en raison de sa grande rigidit\u00e9, de sa solidit\u00e9 et de sa r\u00e9sistance chimique.<\/p>\n<h4>\u00a0<\/h4>\n<h4><strong><b>7. Comment le Nylon 12 CF est-il utilis\u00e9 dans l'industrie a\u00e9rospatiale ?<\/b><\/strong><\/h4>\n<p>Le Nylon 12-CF est utilis\u00e9 dans l'industrie a\u00e9rospatiale pour des composants structurels tels que les longerons d'ailes, les composants de trains d'atterrissage et les pi\u00e8ces de moteur, gr\u00e2ce \u00e0 sa grande rigidit\u00e9, sa solidit\u00e9 et sa r\u00e9sistance \u00e0 la fatigue.<\/p>\n<p>\u00a0<\/p>\n<h4><strong><b>8. Quelles sont les applications m\u00e9dicales qui peuvent b\u00e9n\u00e9ficier du Nylon 12 CF ?<\/b><\/strong><\/h4>\n<p>Le Nylon 12-CF est utilis\u00e9 dans les dispositifs m\u00e9dicaux tels que les implants, les cath\u00e9ters et les instruments chirurgicaux en raison de son excellente biocompatibilit\u00e9 et de sa r\u00e9sistance chimique.<\/p>\n<p>\u00a0<\/p>\n<h4><strong><b>9. Quel r\u00f4le joue le Nylon 12-CF dans l'industrie \u00e9lectrique ?<\/b><\/strong><\/h4>\n<p>Dans l'industrie \u00e9lectrique, le Nylon 12 CF est utilis\u00e9 pour l'isolation \u00e9lectrique, les connecteurs et les disjoncteurs en raison de ses excellentes propri\u00e9t\u00e9s d'isolation \u00e9lectrique et de r\u00e9sistance chimique.<\/p>\n<p>\u00a0<\/p>\n<h4><strong><b>10. Pourquoi le Nylon 12 CF est-il consid\u00e9r\u00e9 comme un polym\u00e8re de haute performance ?<\/b><\/strong><\/h4>\n<p>Le Nylon 12-CF est consid\u00e9r\u00e9 comme un polym\u00e8re de haute performance en raison de ses propri\u00e9t\u00e9s m\u00e9caniques, chimiques, thermiques et de mise en \u0153uvre exceptionnelles, ce qui le rend adapt\u00e9 \u00e0 une large gamme d'applications dans divers secteurs.<\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Propri\u00e9t\u00e9s m\u00e9caniques exceptionnelles du Nylon 12 CF Le Nylon 12 CF offre des propri\u00e9t\u00e9s m\u00e9caniques exceptionnelles qui en font un choix privil\u00e9gi\u00e9 pour les applications de haute performance. Le renforcement en fibres de carbone conf\u00e8re au mat\u00e9riau une rigidit\u00e9 et une r\u00e9sistance \u00e9lev\u00e9es, ce qui permet de l'utiliser dans des applications structurelles o\u00f9 la r\u00e9duction du poids est essentielle. En outre, le Nylon 12 CF pr\u00e9sente une excellente r\u00e9sistance \u00e0 la fatigue, ce qui [...]","protected":false},"author":1,"featured_media":2868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-2865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nylon"],"_links":{"self":[{"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/posts\/2865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/comments?post=2865"}],"version-history":[{"count":2,"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/posts\/2865\/revisions"}],"predecessor-version":[{"id":2869,"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/posts\/2865\/revisions\/2869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/media\/2868"}],"wp:attachment":[{"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/media?parent=2865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/categories?post=2865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nylon-granules.com\/fr\/wp-json\/wp\/v2\/tags?post=2865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}