{"id":1742,"date":"2024-05-29T02:33:44","date_gmt":"2024-05-29T02:33:44","guid":{"rendered":"https:\/\/nylon-granules.com\/?p=1742"},"modified":"2024-05-29T05:38:41","modified_gmt":"2024-05-29T05:38:41","slug":"why-pa66-fr-is-the-top-choice-for-safety-gear","status":"publish","type":"post","link":"https:\/\/nylon-granules.com\/pt\/why-pa66-fr-is-the-top-choice-for-safety-gear\/","title":{"rendered":"Porque \u00e9 que o PA66 FR \u00e9 a melhor escolha para equipamento de seguran\u00e7a"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar o \u00edndice\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nylon-granules.com\/pt\/why-pa66-fr-is-the-top-choice-for-safety-gear\/#Exploring_the_Benefits_of_PA66_FR_in_Safety_Gear\" >Explorando os benef\u00edcios do PA66 FR em equipamentos de seguran\u00e7a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nylon-granules.com\/pt\/why-pa66-fr-is-the-top-choice-for-safety-gear\/#The_Significance_of_PA66_FR\" >O significado da PA66 FR<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nylon-granules.com\/pt\/why-pa66-fr-is-the-top-choice-for-safety-gear\/#Key_Features_of_PA66_FR_Fire_Resistance_and_Durability\" >Principais caracter\u00edsticas do PA66 FR: Resist\u00eancia ao fogo e durabilidade<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nylon-granules.com\/pt\/why-pa66-fr-is-the-top-choice-for-safety-gear\/#Applications_of_PA66_FR_in_Safety_Gear\" >Aplica\u00e7\u00f5es do PA66 FR em equipamentos de seguran\u00e7a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nylon-granules.com\/pt\/why-pa66-fr-is-the-top-choice-for-safety-gear\/#Advantages_Over_Other_Materials_Comparing_PA66_FR_to_Traditional_Materials\" >Vantagens em rela\u00e7\u00e3o a outros materiais: Compara\u00e7\u00e3o do PA66 FR com os materiais tradicionais<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/nylon-granules.com\/pt\/why-pa66-fr-is-the-top-choice-for-safety-gear\/#Addressing_Common_Concerns_Mythbusting_PA66FR_in_Safety_Gear\" >Abordar as preocupa\u00e7\u00f5es comuns: Desmistificando o PA66FR no equipamento de seguran\u00e7a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/nylon-granules.com\/pt\/why-pa66-fr-is-the-top-choice-for-safety-gear\/#Conclusion_Embracing_the_Future_of_Safety_Gear_with_PA66_FR\" >Conclus\u00e3o: Abra\u00e7ando o futuro do equipamento de seguran\u00e7a com PA66 FR<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/nylon-granules.com\/pt\/why-pa66-fr-is-the-top-choice-for-safety-gear\/#FAQ_about_PA66_FR_in_Safety_Gear\" >Perguntas frequentes sobre o PA66 FR no equipamento de seguran\u00e7a<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Exploring_the_Benefits_of_PA66_FR_in_Safety_Gear\"><\/span><strong><b>Explorando os benef\u00edcios do PA66 FR em equipamentos de seguran\u00e7a<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>No mundo atual, dar prioridade \u00e0 seguran\u00e7a \u00e9 fundamental em v\u00e1rios sectores. Desde os bombeiros que lutam contra os infernos at\u00e9 aos trabalhadores da constru\u00e7\u00e3o civil que operam maquinaria pesada, \u00e9 essencial dispor de equipamento de prote\u00e7\u00e3o fi\u00e1vel. Entre os materiais utilizados no equipamento de seguran\u00e7a, <a href=\"https:\/\/nylon-granules.com\/pt\/nylon-plastic-products\/nylon-66\/\">Poliamida 66 (PA66)<\/a> com propriedades retardadoras de chama (FR) destaca-se como uma escolha de topo. Este artigo analisa as raz\u00f5es pelas quais o PA66 FR \u00e9 um fator de mudan\u00e7a no mundo dos equipamentos de seguran\u00e7a, explorando as suas principais caracter\u00edsticas, aplica\u00e7\u00f5es e vantagens em rela\u00e7\u00e3o a outros materiais.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"The_Significance_of_PA66_FR\"><\/span><strong><b>O significado da PA66 FR<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O PA66, tamb\u00e9m conhecido como Nylon 66, \u00e9 um pl\u00e1stico de engenharia robusto e vers\u00e1til, conhecido pelas suas excelentes propriedades mec\u00e2nicas. No entanto, a sua inflamabilidade inerente limita a sua utiliza\u00e7\u00e3o em aplica\u00e7\u00f5es de seguran\u00e7a. \u00c9 aqui que o PA66 FR entra em a\u00e7\u00e3o. Atrav\u00e9s de um processo de modifica\u00e7\u00e3o especializado, o PA66 \u00e9 imbu\u00eddo de aditivos retardadores de chama. Estes aditivos ajudam a suprimir a igni\u00e7\u00e3o, a abrandar a propaga\u00e7\u00e3o da chama e a minimizar a produ\u00e7\u00e3o de fumo durante um inc\u00eandio. Este perfil de seguran\u00e7a melhorado torna-o um componente crucial em v\u00e1rias aplica\u00e7\u00f5es de equipamento de seguran\u00e7a.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Key_Features_of_PA66_FR_Fire_Resistance_and_Durability\"><\/span><strong><b>Principais caracter\u00edsticas do PA66 FR: Resist\u00eancia ao fogo e durabilidade<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A carater\u00edstica que define o PA66 FR \u00e9 a sua resist\u00eancia superior ao fogo. Quando exposto a chamas, derrete em vez de se inflamar facilmente. Este comportamento de auto-extin\u00e7\u00e3o permite ao utilizador ganhar tempo valioso para escapar a uma situa\u00e7\u00e3o de perigo. Al\u00e9m disso, apresenta uma durabilidade excecional. Demonstra uma excelente resist\u00eancia \u00e0 abras\u00e3o, ao desgaste e a produtos qu\u00edmicos agressivos, garantindo a longevidade e a integridade do equipamento de seguran\u00e7a, mesmo em condi\u00e7\u00f5es exigentes.<\/p>\n<p>Al\u00e9m disso, a sua resist\u00eancia ao impacto desempenha um papel importante nas normas de seguran\u00e7a no fabrico de equipamentos. Este material pode resistir a impactos significativos sem comprometer a sua estrutura, oferecendo uma prote\u00e7\u00e3o crucial contra traumatismos por for\u00e7a bruta em caso de acidente.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Applications_of_PA66_FR_in_Safety_Gear\"><\/span><strong><b>Aplica\u00e7\u00f5es do PA66 FR em equipamentos de seguran\u00e7a<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A versatilidade do PA66 FR torna-o um material valioso numa vasta gama de aplica\u00e7\u00f5es de equipamentos de seguran\u00e7a. Eis alguns exemplos proeminentes:<\/p>\n<ul>\n<li><strong>Vestu\u00e1rio de combate a inc\u00eandios:<\/strong>\u00c9 um material fundamental no vestu\u00e1rio dos bombeiros, incluindo casacos, cal\u00e7as e capacetes. A sua resist\u00eancia \u00e0 chama oferece uma prote\u00e7\u00e3o crucial contra o calor e as chamas, enquanto a sua durabilidade garante que o equipamento pode suportar os rigores do combate aos inc\u00eandios.<\/li>\n<li><strong>Equipamento de seguran\u00e7a industrial:<\/strong>\u00c9 adequado para v\u00e1rios equipamentos de seguran\u00e7a industrial, incluindo fatos de arco voltaico, capacetes de soldadura e equipamento contra salpicos de produtos qu\u00edmicos. A sua capacidade de resistir a chamas, produtos qu\u00edmicos e impactos protege os trabalhadores em ambientes perigosos.<\/li>\n<li><strong>Equipamento de seguran\u00e7a el\u00e9ctrica:<\/strong>\u00c9 um material preferido para componentes de isolamento el\u00e9trico em equipamento de seguran\u00e7a. A sua resist\u00eancia el\u00e9ctrica inerente ajuda a evitar choques el\u00e9ctricos, uma preocupa\u00e7\u00e3o importante no trabalho el\u00e9trico.<\/li>\n<li><strong>Equipamento de prote\u00e7\u00e3o individual (EPI):<\/strong>Encontra aplica\u00e7\u00e3o em v\u00e1rios EPI, tais como capacetes, \u00f3culos de prote\u00e7\u00e3o e coletes bal\u00edsticos. A resist\u00eancia ao impacto e a durabilidade do material oferecem uma maior prote\u00e7\u00e3o contra ferimentos na cabe\u00e7a, detritos voadores e proj\u00e9cteis.<\/li>\n<\/ul>\n<p>Para al\u00e9m das suas principais vantagens em termos de seguran\u00e7a, pode contribuir para um melhor desempenho do equipamento de seguran\u00e7a. A sua natureza leve permite uma maior mobilidade e conforto, factores cruciais para tempos de utiliza\u00e7\u00e3o prolongados. Al\u00e9m disso, apresenta uma boa estabilidade dimensional, garantindo que o equipamento mant\u00e9m o seu ajuste e funcionalidade mesmo em condi\u00e7\u00f5es extremas.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Advantages_Over_Other_Materials_Comparing_PA66_FR_to_Traditional_Materials\"><\/span><strong><b>Vantagens em rela\u00e7\u00e3o a outros materiais: Compara\u00e7\u00e3o do PA66 FR com os materiais tradicionais<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Embora outros materiais possam ser utilizados no equipamento de seguran\u00e7a, o PA66FR oferece vantagens distintas. Os materiais tradicionais, como o algod\u00e3o e as fibras de aramida, embora sejam retardadores de chama, requerem frequentemente tratamentos qu\u00edmicos adicionais. Estes tratamentos podem deteriorar-se com o tempo, diminuindo a resist\u00eancia \u00e0 chama do equipamento. O PA66FR, por outro lado, incorpora as propriedades retardadoras de chama na estrutura do pol\u00edmero, garantindo um desempenho de seguran\u00e7a duradouro.<\/p>\n<p>Outra vantagem do PA66FR \u00e9 a sua sustentabilidade. Em compara\u00e7\u00e3o com alguns outros materiais, oferece um bom potencial de reciclagem, contribuindo para uma abordagem mais consciente do ambiente na produ\u00e7\u00e3o de equipamentos de seguran\u00e7a. Al\u00e9m disso, a sua durabilidade reduz a necessidade de substitui\u00e7\u00f5es frequentes, minimizando ainda mais o impacto ambiental.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Addressing_Common_Concerns_Mythbusting_PA66FR_in_Safety_Gear\"><\/span><strong><b>Abordar as preocupa\u00e7\u00f5es comuns: Desmistificando o PA66FR no equipamento de seguran\u00e7a<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Apesar das suas in\u00fameras vantagens, o PA66FR suscita algumas preocupa\u00e7\u00f5es. Um equ\u00edvoco comum \u00e9 o facto de poder evitar completamente as queimaduras. Isto n\u00e3o \u00e9 inteiramente verdade. Embora o PA66 FR atrase significativamente a igni\u00e7\u00e3o e a propaga\u00e7\u00e3o da chama, a exposi\u00e7\u00e3o prolongada a calor extremo pode ainda causar queimaduras. Por conseguinte, \u00e9 crucial seguir os protocolos de seguran\u00e7a adequados e utilizar o equipamento em conjunto com outras medidas de seguran\u00e7a.<\/p>\n<p>Outra preocupa\u00e7\u00e3o \u00e9 a possibilidade de o PA66 FR derreter durante um inc\u00eandio. Embora a fus\u00e3o seja uma carater\u00edstica do material, ela desempenha um papel vital na seguran\u00e7a. A fus\u00e3o cria uma barreira entre as chamas e a pele do utilizador, proporcionando prote\u00e7\u00e3o adicional e tempo para escapar. \u00c9 importante lembrar que o equipamento de seguran\u00e7a foi concebido para oferecer prote\u00e7\u00e3o, mas n\u00e3o imunidade total, contra os perigos.<\/p>\n<p>Para garantir a efic\u00e1cia do PA66 FR no equipamento de seguran\u00e7a, \u00e9 fundamental respeitar as normas de conformidade de qualidade e seguran\u00e7a. Os fabricantes de renome utilizam PA66 FR de alta qualidade com aditivos retardadores de chama adequados. O equipamento \u00e9 submetido a testes rigorosos para cumprir as certifica\u00e7\u00f5es de seguran\u00e7a relevantes, garantindo a sua capacidade de resistir ao fogo e a outros perigos.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion_Embracing_the_Future_of_Safety_Gear_with_PA66_FR\"><\/span><strong><b>Conclus\u00e3o: Abra\u00e7ando o futuro do equipamento de seguran\u00e7a com PA66 FR <\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O PA66FR revolucionou a ind\u00fastria dos equipamentos de seguran\u00e7a ao fornecer um material robusto que d\u00e1 prioridade \u00e0 seguran\u00e7a do utilizador. A sua excecional resist\u00eancia ao fogo, durabilidade e versatilidade fazem dele a escolha preferida para v\u00e1rias aplica\u00e7\u00f5es de seguran\u00e7a. Para al\u00e9m das suas utiliza\u00e7\u00f5es actuais, os avan\u00e7os na tecnologia PA66FR est\u00e3o continuamente em curso. Os investigadores est\u00e3o a explorar formas de melhorar ainda mais a sua resist\u00eancia \u00e0 chama, toler\u00e2ncia ao calor e propriedades de leveza. Al\u00e9m disso, o foco em pr\u00e1ticas de fabrico sustent\u00e1veis abre portas para o desenvolvimento de variantes de PA66FR ainda mais ecol\u00f3gicas.<\/p>\n<p>O futuro dos equipamentos de seguran\u00e7a \u00e9, sem d\u00favida, brilhante, com o PA66FR a desempenhar um papel de lideran\u00e7a. \u00c0 medida que as inova\u00e7\u00f5es continuam, podemos esperar equipamentos de prote\u00e7\u00e3o ainda mais avan\u00e7ados e eficazes para proteger os utilizadores em diversas ind\u00fastrias.<\/p>\n<h3><strong><b>\u00a0<\/b><\/strong><\/h3>\n<h2><span class=\"ez-toc-section\" id=\"FAQ_about_PA66_FR_in_Safety_Gear\"><\/span><strong><b>Perguntas frequentes sobre o PA66 FR no equipamento de seguran\u00e7a<\/b><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ol>\n<li><strong> \u00c9 seguro usar o PA66FR durante longos per\u00edodos de tempo?<\/strong><\/li>\n<\/ol>\n<p>O PA66 FR \u00e9 geralmente considerado seguro para utiliza\u00e7\u00e3o prolongada. No entanto, as considera\u00e7\u00f5es de seguran\u00e7a espec\u00edficas podem variar consoante a conce\u00e7\u00e3o e a aplica\u00e7\u00e3o do equipamento de seguran\u00e7a. \u00c9 importante seguir as recomenda\u00e7\u00f5es do fabricante em mat\u00e9ria de limpeza e manuten\u00e7\u00e3o para garantir a integridade e a seguran\u00e7a do equipamento ao longo do tempo.<\/p>\n<p>\u00a0<\/p>\n<ol start=\"2\">\n<li><strong> Como \u00e9 que o PA66FR se compara a outros materiais retardadores de chama em termos de custo?<\/strong><\/li>\n<\/ol>\n<p>Embora o custo inicial do PA66 FR possa ser ligeiramente mais elevado do que o de alguns materiais tradicionais, a sua durabilidade e resist\u00eancia duradoura \u00e0s chamas podem traduzir-se em poupan\u00e7as de custos a longo prazo. A frequ\u00eancia de substitui\u00e7\u00e3o reduzida e os requisitos m\u00ednimos de manuten\u00e7\u00e3o contribuem para a rela\u00e7\u00e3o custo-efic\u00e1cia global do equipamento de seguran\u00e7a PA66 FR.<\/p>\n<ol start=\"3\">\n<li><strong> O PA66FR pode ser reciclado?<\/strong><\/li>\n<\/ol>\n<p>Sim, o PA66 FR possui um bom potencial de reciclagem. No entanto, os processos de reciclagem espec\u00edficos podem variar consoante os aditivos utilizados no material e os regulamentos locais. Procure fabricantes empenhados em pr\u00e1ticas sustent\u00e1veis e explore op\u00e7\u00f5es para uma gest\u00e3o respons\u00e1vel do fim de vida \u00fatil do equipamento de seguran\u00e7a PA66 FR.<\/p>\n<p>\u00a0<\/p>\n<ol start=\"4\">\n<li><strong> Onde posso obter mais informa\u00e7\u00f5es sobre o equipamento de seguran\u00e7a PA66FR?<\/strong><\/li>\n<\/ol>\n<p>Os fabricantes de equipamentos de seguran\u00e7a e os fornecedores de equipamentos de seguran\u00e7a de renome podem fornecer informa\u00e7\u00f5es detalhadas sobre os produtos PA66FR espec\u00edficos que oferecem. Al\u00e9m disso, as associa\u00e7\u00f5es industriais e os organismos reguladores publicam frequentemente recursos sobre materiais e normas de equipamento de seguran\u00e7a.<\/p>","protected":false},"excerpt":{"rendered":"<p>Explorar as vantagens do PA66 FR no equipamento de seguran\u00e7a No mundo atual, a prioridade \u00e0 seguran\u00e7a \u00e9 fundamental em v\u00e1rios sectores. Desde os bombeiros que lutam contra os infernos at\u00e9 aos trabalhadores da constru\u00e7\u00e3o civil que operam maquinaria pesada, \u00e9 essencial dispor de equipamento de prote\u00e7\u00e3o fi\u00e1vel. Entre os materiais utilizados no equipamento de seguran\u00e7a, a Poliamida 66 (PA66) com propriedades retardadoras de chama (FR) destaca-se como uma escolha de topo. Este [...]","protected":false},"author":1,"featured_media":1744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/posts\/1742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/comments?post=1742"}],"version-history":[{"count":8,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/posts\/1742\/revisions"}],"predecessor-version":[{"id":1752,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/posts\/1742\/revisions\/1752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/media\/1744"}],"wp:attachment":[{"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/media?parent=1742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/categories?post=1742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/tags?post=1742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}