{"id":2884,"date":"2024-07-18T01:35:20","date_gmt":"2024-07-18T01:35:20","guid":{"rendered":"https:\/\/nylon-granules.com\/?p=2884"},"modified":"2024-07-18T01:54:11","modified_gmt":"2024-07-18T01:54:11","slug":"is-nylon-pa12-strong","status":"publish","type":"post","link":"https:\/\/nylon-granules.com\/pt\/is-nylon-pa12-strong\/","title":{"rendered":"O nylon PA12 \u00e9 forte?"},"content":{"rendered":"<div class=\"row\"  id=\"row-1829830877\">\n\n\t<div id=\"col-404435723\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar o \u00edndice\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nylon-granules.com\/pt\/is-nylon-pa12-strong\/#Introduction_of_Nylon_PA12\" >Introdu\u00e7\u00e3o do Nylon PA12<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nylon-granules.com\/pt\/is-nylon-pa12-strong\/#Molecular_Structure_and_Mechanical_Properties_of_Nylon_PA12\" >Estrutura molecular e propriedades mec\u00e2nicas do nylon PA12<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nylon-granules.com\/pt\/is-nylon-pa12-strong\/#High_Tensile_Strength_Of_Nylon_PA12\" >Alta resist\u00eancia \u00e0 tra\u00e7\u00e3o do nylon PA12<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nylon-granules.com\/pt\/is-nylon-pa12-strong\/#Superior_Stiffness_of_Nylon_PA12\" >Rigidez superior do Nylon PA12<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nylon-granules.com\/pt\/is-nylon-pa12-strong\/#Exceptional_Impact_Resistance_of_Nylon_PA12\" >Resist\u00eancia excecional ao impacto do Nylon PA12<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/nylon-granules.com\/pt\/is-nylon-pa12-strong\/#Nylon_PA12_Applications_in_Various_Industries\" >Aplica\u00e7\u00f5es do Nylon PA12 em v\u00e1rios sectores\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/nylon-granules.com\/pt\/is-nylon-pa12-strong\/#Conclusion_of_Nylon_PA12\" >Conclus\u00e3o do Nylon PA12<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/nylon-granules.com\/pt\/is-nylon-pa12-strong\/#FAQ_Nylon_PA12\" >FAQ: Nylon PA12<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Introduction_of_Nylon_PA12\"><\/span><strong>Introdu\u00e7\u00e3o do Nylon PA12<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O nylon PA12, tamb\u00e9m conhecido como poliamida 12, \u00e9 um pol\u00edmero de alto desempenho conhecido pela sua excecional resist\u00eancia e durabilidade. Amplamente utilizado em v\u00e1rias ind\u00fastrias, incluindo os sectores aeroespacial, autom\u00f3vel e m\u00e9dico, este material avan\u00e7ado \u00e9 preferido quando os pl\u00e1sticos de alto desempenho s\u00e3o essenciais. Este artigo analisa a resist\u00eancia do Nylon PA12 e explica porque \u00e9 que se destaca como um material superior.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-44020813\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_389550720\">\n\t\t<a class=\"\" href=\"https:\/\/nylon-granules.com\/pt\/products\/nylon-12\/pa12-resin\/\" >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"846\" height=\"1128\" src=\"https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-PA12.jpg\" class=\"attachment-original size-original\" alt=\"Nylon PA12\" srcset=\"https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-PA12.jpg 846w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-PA12-225x300.jpg 225w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-PA12-768x1024.jpg 768w, https:\/\/nylon-granules.com\/wp-content\/uploads\/2024\/07\/Nylon-PA12-9x12.jpg 9w\" sizes=\"auto, (max-width: 846px) 100vw, 846px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_389550720 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"w-full text-token-text-primary\" dir=\"auto\" data-testid=\"conversation-turn-3\" data-scroll-anchor=\"false\">\n<div class=\"text-base py-[18px] px-3 md:px-4 m-auto md:px-5 lg:px-1 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-4 text-base md:gap-5 lg:gap-6 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem]\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex w-full flex-col items-end gap-2 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"e1bceaa1-b571-4276-b020-cad02aedbcbb\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h2><span class=\"ez-toc-section\" id=\"Molecular_Structure_and_Mechanical_Properties_of_Nylon_PA12\"><\/span><strong>Estrutura molecular e propriedades mec\u00e2nicas do nylon PA12<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u00c9 um pol\u00edmero semi-cristalino com propriedades mec\u00e2nicas excepcionais, tais como elevada resist\u00eancia \u00e0 tra\u00e7\u00e3o, rigidez e resist\u00eancia ao impacto. A sua resist\u00eancia deriva da sua estrutura molecular \u00fanica, composta por grupos amida repetidos (-CONH-) ligados por \u00e1tomos de carbono. Esta configura\u00e7\u00e3o resulta num elevado grau de cristalinidade, criando uma estrutura molecular densa e bem compactada. Al\u00e9m disso, esta estrutura confere ao Nylon PA12 uma excelente resist\u00eancia \u00e0 flu\u00eancia, permitindo-lhe manter a sua forma e dimens\u00f5es sob cargas sustentadas.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"High_Tensile_Strength_Of_Nylon_PA12\"><\/span><strong>Alta resist\u00eancia \u00e0 tra\u00e7\u00e3o do nylon PA12<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Um atributo cr\u00edtico do PA12 \u00e9 a sua elevada resist\u00eancia \u00e0 tra\u00e7\u00e3o, que varia entre 80 e 120 MPa, dependendo do tipo e do processo de fabrico. Este valor \u00e9 significativamente superior ao de outros pol\u00edmeros normalmente utilizados, como o polipropileno e o polietileno, que t\u00eam uma resist\u00eancia \u00e0 tra\u00e7\u00e3o de cerca de 35 MPa e 25 MPa, respetivamente. A elevada resist\u00eancia \u00e0 tra\u00e7\u00e3o do PA12 torna-o ideal para aplica\u00e7\u00f5es que envolvem cargas elevadas, como engrenagens, rolamentos e fixadores.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Superior_Stiffness_of_Nylon_PA12\"><\/span><strong>Rigidez superior de\u00a0<\/strong><strong>Nylon PA12<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A elevada rigidez do PA12, que varia entre 8 e 12 GPa, \u00e9 outro fator que contribui para a sua resist\u00eancia. Este valor \u00e9 muito superior \u00e0 rigidez do polipropileno (1,5 GPa) e do polietileno (0,3 GPa). A elevada rigidez do material torna-o adequado para componentes estruturais e aplica\u00e7\u00f5es de suporte de carga, onde a rigidez \u00e9 essencial.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Exceptional_Impact_Resistance_of_Nylon_PA12\"><\/span><strong>Resist\u00eancia excecional ao impacto de <\/strong><strong>Nylon PA12<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Para al\u00e9m da sua resist\u00eancia \u00e0 tra\u00e7\u00e3o e rigidez, o PA12 oferece tamb\u00e9m uma excelente resist\u00eancia ao impacto. Esta carater\u00edstica deve-se ao seu elevado peso molecular e cristalinidade significativa, que criam uma estrutura molecular densa e r\u00edgida. Estas propriedades conferem ao material a capacidade de resistir eficazmente aos impactos, tornando-o uma escolha fi\u00e1vel para aplica\u00e7\u00f5es exigentes.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Nylon_PA12_Applications_in_Various_Industries\"><\/span><strong>Nylon PA12 <\/strong><strong>Aplica\u00e7\u00f5es em v\u00e1rios sectores\u00a0<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A excelente resist\u00eancia e durabilidade do PA12 fazem dele um material preferido em v\u00e1rios sectores. Na ind\u00fastria aeroespacial, \u00e9 utilizado em componentes de motores, trens de aterragem e pe\u00e7as estruturais devido \u00e0 sua elevada rela\u00e7\u00e3o for\u00e7a\/peso e resist\u00eancia \u00e0 flu\u00eancia. Na ind\u00fastria autom\u00f3vel, encontra-se em componentes de motores e transmiss\u00f5es, bem como em pe\u00e7as estruturais, devido \u00e0 sua for\u00e7a, rigidez e resist\u00eancia ao impacto. No sector m\u00e9dico, o PA12 \u00e9 utilizado em implantes, instrumentos cir\u00fargicos e dispositivos m\u00e9dicos, gra\u00e7as \u00e0 sua biocompatibilidade e excelentes propriedades mec\u00e2nicas.<\/p>\n<p>\u00a0<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion_of_Nylon_PA12\"><\/span><strong>Conclus\u00e3o de <\/strong><a href=\"https:\/\/nylon-granules.com\/pt\/products\/nylon-12\/\"><strong>Nylon PA12<\/strong><\/a><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O Nylon PA12 \u00e9 um pol\u00edmero de alto desempenho que oferece uma resist\u00eancia e durabilidade excepcionais. A sua elevada resist\u00eancia \u00e0 tra\u00e7\u00e3o, rigidez e resist\u00eancia ao impacto fazem dele uma escolha de topo para v\u00e1rias aplica\u00e7\u00f5es, especialmente nas ind\u00fastrias aeroespacial, autom\u00f3vel e m\u00e9dica. Estas qualidades superiores s\u00e3o atribu\u00eddas \u00e0 sua estrutura molecular \u00fanica, que apresenta grupos amida repetidos ligados por \u00e1tomos de carbono. \u00c0 medida que a procura de pl\u00e1sticos de alto desempenho cresce, espera-se que a utiliza\u00e7\u00e3o do PA12 aumente em v\u00e1rios sectores.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"mt-1 flex gap-3 empty:hidden ml-3\">\n<div class=\"items-center justify-start rounded-xl p-1 z-10 -mt-1 bg-token-main-surface-primary md:absolute md:border md:border-token-border-light flex\">\u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"w-full text-token-text-primary\" dir=\"auto\" data-testid=\"conversation-turn-5\" data-scroll-anchor=\"true\">\n<div class=\"text-base py-[18px] px-3 md:px-4 m-auto md:px-5 lg:px-1 xl:px-5\">\n<div class=\"mx-auto flex flex-1 gap-4 text-base md:gap-5 lg:gap-6 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem]\">\n<div class=\"flex-shrink-0 flex flex-col relative items-end\">\n<div>\n<div class=\"pt-0\">\n<div class=\"gizmo-bot-avatar flex h-8 w-8 items-center justify-center overflow-hidden rounded-full\">\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">\u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex w-full flex-col items-end gap-2 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"2c96e147-cdfb-4363-86e9-a657e446e6dc\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h2><span class=\"ez-toc-section\" id=\"FAQ_Nylon_PA12\"><\/span><strong>FAQ: Nylon PA12<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>1. O que \u00e9 o Nylon PA12?<\/strong><\/p>\n<p>R: O PA12, tamb\u00e9m conhecido como poliamida 12, \u00e9 um pol\u00edmero de alto desempenho conhecido pela sua excecional resist\u00eancia e durabilidade. \u00c9 amplamente utilizado em v\u00e1rias ind\u00fastrias que requerem pl\u00e1sticos de alto desempenho.<\/p>\n<p>\u00a0<\/p>\n<p><strong>2. Quais s\u00e3o as principais propriedades mec\u00e2nicas do Nylon PA12?<\/strong><\/p>\n<p>R: O PA12 apresenta elevada resist\u00eancia \u00e0 tra\u00e7\u00e3o (80-120 MPa), elevada rigidez (8-12 GPa) e excelente resist\u00eancia ao impacto devido \u00e0 sua estrutura molecular \u00fanica e elevado grau de cristalinidade.<\/p>\n<p>\u00a0<\/p>\n<p><strong>3. Porque \u00e9 que o Nylon PA12 \u00e9 considerado forte?<\/strong><\/p>\n<p>R: A resist\u00eancia da PA12 prov\u00e9m da sua estrutura molecular semi-cristalina, que apresenta grupos amida repetidos ligados por \u00e1tomos de carbono. Isto resulta numa estrutura densa e bem compactada, melhorando as suas propriedades mec\u00e2nicas.<\/p>\n<p>\u00a0<\/p>\n<p><strong>4. Como \u00e9 que o Nylon PA12 se compara a outros pol\u00edmeros como o polipropileno e o polietileno?<\/strong><\/p>\n<p>R: O PA12 tem uma resist\u00eancia \u00e0 tra\u00e7\u00e3o e uma rigidez significativamente mais elevadas do que o polipropileno e o polietileno. A sua resist\u00eancia \u00e0 tra\u00e7\u00e3o varia entre 80-120 MPa, enquanto o polipropileno e o polietileno t\u00eam uma resist\u00eancia \u00e0 tra\u00e7\u00e3o de cerca de 35 MPa e 25 MPa, respetivamente. A rigidez do PA12 (8-12 GPa) tamb\u00e9m excede largamente a do polipropileno (1,5 GPa) e do polietileno (0,3 GPa).<\/p>\n<p>\u00a0<\/p>\n<p><strong>5. Que aplica\u00e7\u00f5es beneficiam da utiliza\u00e7\u00e3o do Nylon PA12?<\/strong><\/p>\n<p>R: O PA12 \u00e9 utilizado nas ind\u00fastrias aeroespacial (componentes de motores, trens de aterragem, componentes estruturais), autom\u00f3vel (componentes de motores e transmiss\u00f5es, pe\u00e7as estruturais) e m\u00e9dica (implantes, instrumentos cir\u00fargicos, dispositivos m\u00e9dicos) devido \u00e0 sua elevada resist\u00eancia, rigidez, resist\u00eancia ao impacto e biocompatibilidade.<\/p>\n<p>\u00a0<\/p>\n<p><strong>6. O que torna o PA12 adequado para aplica\u00e7\u00f5es de carga elevada?<\/strong><\/p>\n<p>R: A sua elevada resist\u00eancia \u00e0 tra\u00e7\u00e3o e rigidez tornam o PA12 adequado para aplica\u00e7\u00f5es de carga elevada, como engrenagens, rolamentos e fixadores.<\/p>\n<p>\u00a0<\/p>\n<p><strong>7. O que \u00e9 que contribui para a resist\u00eancia ao impacto do Nylon PA12?<\/strong><\/p>\n<p>R: O elevado peso molecular e o grau de cristalinidade do PA12 resultam numa estrutura molecular densa e bem compactada, proporcionando uma excelente resist\u00eancia ao impacto.<\/p>\n<p>\u00a0<\/p>\n<p><strong>8. Prev\u00ea-se que a procura de Nylon PA12 aumente?<\/strong><\/p>\n<p>R: Sim, \u00e0 medida que a necessidade de pl\u00e1sticos de alto desempenho aumenta em v\u00e1rios sectores, espera-se que a utiliza\u00e7\u00e3o de PA12 aumente devido \u00e0s suas propriedades mec\u00e2nicas superiores.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Estrutura molecular e propriedades mec\u00e2nicas do Nylon PA12 \u00c9 um pol\u00edmero semi-cristalino com propriedades mec\u00e2nicas excepcionais, tais como elevada resist\u00eancia \u00e0 tra\u00e7\u00e3o, rigidez e resist\u00eancia ao impacto. A sua resist\u00eancia \u00e9 derivada da sua estrutura molecular \u00fanica, composta por grupos amida repetidos (-CONH-) ligados por \u00e1tomos de carbono. Esta configura\u00e7\u00e3o resulta num elevado grau de cristalinidade, criando [...]","protected":false},"author":1,"featured_media":2886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[],"class_list":["post-2884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nylon"],"_links":{"self":[{"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/posts\/2884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/comments?post=2884"}],"version-history":[{"count":2,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/posts\/2884\/revisions"}],"predecessor-version":[{"id":2888,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/posts\/2884\/revisions\/2888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/media\/2886"}],"wp:attachment":[{"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/media?parent=2884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/categories?post=2884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nylon-granules.com\/pt\/wp-json\/wp\/v2\/tags?post=2884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}